{"id":5952,"date":"2023-07-14T14:10:03","date_gmt":"2023-07-14T12:10:03","guid":{"rendered":"https:\/\/www.sjr-erlangen.de\/WP\/?post_type=tribe_events&#038;p=5952"},"modified":"2024-11-14T17:53:55","modified_gmt":"2024-11-14T16:53:55","slug":"digital-total-digitalschulung-fuer-jugendleiterinnen","status":"publish","type":"tribe_events","link":"https:\/\/www.sjr-erlangen.de\/WP\/event\/digital-total-digitalschulung-fuer-jugendleiterinnen\/","title":{"rendered":"ENTF\u00c4LLT &#8211; DIGITAL TOTAL &#8211; DIGITALSCHULUNG F\u00dcR JUGENDLEITER*INNEN"},"content":{"rendered":"<p>DIGITALSCHULUNG F\u00dcR JUGENDLEITER*INNEN<\/p>\n<p>Digital Total ist eine Mischung aus Ausprobieren und Erlernen neuer digitaler Methoden,\u00a0welche die Arbeit mit Jugendlichen spannend und ergebnisreich machen k\u00f6nnen.<\/p>\n<p>Der Stadtjugendring hat einen beachtlichen Digital-Verleih-Katalog angesammelt. Dieser umfasst u. a. Virtual-Reality-Brillen, Fotogrammetrie, Minecraft, Gaming-Rechner, eine Foto- und Filmdrohne sowie eine 360-Grad-Kamera zur Anwendung auf Smartphone und iPads. Damit wir das Material mit gutem Gewissen rausgeben k\u00f6nnen und es im Einsatz das gew\u00fcnschte Ergebnis erzielt, veranstaltet der SJR dazu eine Schulung.<\/p>\n<p>Auch wollen wir gerne unser anwendungsbezogenes Wissen zu Programmen und Onlineplattformen teilen.<\/p>\n<p>Auf Seiten der Methodenkompetenz werden Beispiele aus der interreligi\u00f6sen, interkulturellen und queeren Jugendarbeit vorgef\u00fchrt. Dies dient der Kl\u00e4rung der Frage: &#8222;Und was kann man damit machen?&#8220;. Im Wechsel werden die verschiedenen Stationen besucht und das Material selbst ausprobiert.<\/p>\n<p>Nach dem Erlernen der Methoden wollen wir mit euch gemeinsam frei experimentieren. Wir beginnen um 21:00 Uhr. Es kann dann schon ein bisschen sp\u00e4ter werden.<\/p>\n<p>Das Programm ist geeignet f\u00fcr Digitalinteressierte und Menschen mit Vorerfahrung. F\u00fcr Teilnehmer*innen, welche 2023 an Programmen des Stadtjugendrings als Betreuende teilnahmen, ist das Programm kostenlos. Die Schulung ist Voraussetzung zum Verleih des VR-Materials (Virtual Reality).<\/p>\n<p>In diesem Jahr freuen wir uns sehr, &#8222;Augenblick mal!&#8220; als Partner gewonnen zu haben. Es werden interaktive Szenen von Diskriminierungssituationen, welche von Betroffenen erstellt wurden, in VR gezeigt und gemeinsam nachbesprochen.<\/p>\n<p>FACTS<\/p>\n<p>WER:\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 min. 6 max. 15 Personen ab 14 Jahren<\/p>\n<p>WANN:\u00a0 \u00a0 ENTF\u00c4LLT Fr. 06.12.2024, 21:00 Uhr, das Ende der Veranstaltung ist offen<\/p>\n<p>WO:\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 SJR Gesch\u00e4ftsstelle, Michael-Vogel-Str. 1e, Erlangen<\/p>\n<p>EUR:\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 15,00 pro Person *siehe oben<\/p>\n","protected":false},"excerpt":{"rendered":"<p>DIGITALSCHULUNG F\u00dcR JUGENDLEITER*INNEN Digital Total ist eine Mischung aus Ausprobieren und Erlernen neuer digitaler Methoden,\u00a0welche die Arbeit mit Jugendlichen spannend und ergebnisreich machen k\u00f6nnen. Der Stadtjugendring hat einen beachtlichen Digital-Verleih-Katalog [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5953,"template":"","meta":{"ocean_post_layout":"","ocean_both_sidebars_style":"","ocean_both_sidebars_content_width":0,"ocean_both_sidebars_sidebars_width":0,"ocean_sidebar":"","ocean_second_sidebar":"","ocean_disable_margins":"enable","ocean_add_body_class":"","ocean_shortcode_before_top_bar":"","ocean_shortcode_after_top_bar":"","ocean_shortcode_before_header":"","ocean_shortcode_after_header":"","ocean_has_shortcode":"","ocean_shortcode_after_title":"","ocean_shortcode_before_footer_widgets":"","ocean_shortcode_after_footer_widgets":"","ocean_shortcode_before_footer_bottom":"","ocean_shortcode_after_footer_bottom":"","ocean_display_top_bar":"default","ocean_display_header":"default","ocean_header_style":"","ocean_center_header_left_menu":"","ocean_custom_header_template":"","ocean_custom_logo":0,"ocean_custom_retina_logo":0,"ocean_custom_logo_max_width":0,"ocean_custom_logo_tablet_max_width":0,"ocean_custom_logo_mobile_max_width":0,"ocean_custom_logo_max_height":0,"ocean_custom_logo_tablet_max_height":0,"ocean_custom_logo_mobile_max_height":0,"ocean_header_custom_menu":"","ocean_menu_typo_font_family":"","ocean_menu_typo_font_subset":"","ocean_menu_typo_font_size":0,"ocean_menu_typo_font_size_tablet":0,"ocean_menu_typo_font_size_mobile":0,"ocean_menu_typo_font_size_unit":"px","ocean_menu_typo_font_weight":"","ocean_menu_typo_font_weight_tablet":"","ocean_menu_typo_font_weight_mobile":"","ocean_menu_typo_transform":"","ocean_menu_typo_transform_tablet":"","ocean_menu_typo_transform_mobile":"","ocean_menu_typo_line_height":0,"ocean_menu_typo_line_height_tablet":0,"ocean_menu_typo_line_height_mobile":0,"ocean_menu_typo_line_height_unit":"","ocean_menu_typo_spacing":0,"ocean_menu_typo_spacing_tablet":0,"ocean_menu_typo_spacing_mobile":0,"ocean_menu_typo_spacing_unit":"","ocean_menu_link_color":"","ocean_menu_link_color_hover":"","ocean_menu_link_color_active":"","ocean_menu_link_background":"","ocean_menu_link_hover_background":"","ocean_menu_link_active_background":"","ocean_menu_social_links_bg":"","ocean_menu_social_hover_links_bg":"","ocean_menu_social_links_color":"","ocean_menu_social_hover_links_color":"","ocean_disable_title":"default","ocean_disable_heading":"default","ocean_post_title":"","ocean_post_subheading":"","ocean_post_title_style":"","ocean_post_title_background_color":"","ocean_post_title_background":0,"ocean_post_title_bg_image_position":"","ocean_post_title_bg_image_attachment":"","ocean_post_title_bg_image_repeat":"","ocean_post_title_bg_image_size":"","ocean_post_title_height":0,"ocean_post_title_bg_overlay":0.5,"ocean_post_title_bg_overlay_color":"","ocean_disable_breadcrumbs":"default","ocean_breadcrumbs_color":"","ocean_breadcrumbs_separator_color":"","ocean_breadcrumbs_links_color":"","ocean_breadcrumbs_links_hover_color":"","ocean_display_footer_widgets":"default","ocean_display_footer_bottom":"default","ocean_custom_footer_template":"","_tribe_events_status":"","_tribe_events_status_reason":"","footnotes":""},"tags":[],"tribe_events_cat":[],"class_list":["post-5952","tribe_events","type-tribe_events","status-publish","has-post-thumbnail","hentry","entry","has-media"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>ENTF\u00c4LLT - DIGITAL TOTAL - DIGITALSCHULUNG F\u00dcR JUGENDLEITER*INNEN - SJR Erlangen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.sjr-erlangen.de\/WP\/event\/digital-total-digitalschulung-fuer-jugendleiterinnen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"ENTF\u00c4LLT - DIGITAL TOTAL - DIGITALSCHULUNG F\u00dcR JUGENDLEITER*INNEN - SJR Erlangen\" \/>\n<meta property=\"og:description\" content=\"DIGITALSCHULUNG F\u00dcR JUGENDLEITER*INNEN Digital Total ist eine Mischung aus Ausprobieren und Erlernen neuer digitaler Methoden,\u00a0welche die Arbeit mit Jugendlichen spannend und ergebnisreich machen k\u00f6nnen. Der Stadtjugendring hat einen beachtlichen Digital-Verleih-Katalog [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.sjr-erlangen.de\/WP\/event\/digital-total-digitalschulung-fuer-jugendleiterinnen\/\" \/>\n<meta property=\"og:site_name\" content=\"SJR Erlangen\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-14T16:53:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.sjr-erlangen.de\/WP\/wp-content\/uploads\/2023\/07\/DigitalTotal.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"300\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.sjr-erlangen.de\\\/WP\\\/event\\\/digital-total-digitalschulung-fuer-jugendleiterinnen\\\/\",\"url\":\"https:\\\/\\\/www.sjr-erlangen.de\\\/WP\\\/event\\\/digital-total-digitalschulung-fuer-jugendleiterinnen\\\/\",\"name\":\"ENTF\u00c4LLT - DIGITAL TOTAL - DIGITALSCHULUNG F\u00dcR JUGENDLEITER*INNEN - SJR Erlangen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.sjr-erlangen.de\\\/WP\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.sjr-erlangen.de\\\/WP\\\/event\\\/digital-total-digitalschulung-fuer-jugendleiterinnen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.sjr-erlangen.de\\\/WP\\\/event\\\/digital-total-digitalschulung-fuer-jugendleiterinnen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.sjr-erlangen.de\\\/WP\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/DigitalTotal.jpg\",\"datePublished\":\"2023-07-14T12:10:03+00:00\",\"dateModified\":\"2024-11-14T16:53:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.sjr-erlangen.de\\\/WP\\\/event\\\/digital-total-digitalschulung-fuer-jugendleiterinnen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.sjr-erlangen.de\\\/WP\\\/event\\\/digital-total-digitalschulung-fuer-jugendleiterinnen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/www.sjr-erlangen.de\\\/WP\\\/event\\\/digital-total-digitalschulung-fuer-jugendleiterinnen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.sjr-erlangen.de\\\/WP\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/DigitalTotal.jpg\",\"contentUrl\":\"https:\\\/\\\/www.sjr-erlangen.de\\\/WP\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/DigitalTotal.jpg\",\"width\":300,\"height\":200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.sjr-erlangen.de\\\/WP\\\/event\\\/digital-total-digitalschulung-fuer-jugendleiterinnen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/www.sjr-erlangen.de\\\/WP\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Veranstaltungen\",\"item\":\"https:\\\/\\\/www.sjr-erlangen.de\\\/WP\\\/events\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"ENTF\u00c4LLT &#8211; DIGITAL TOTAL &#8211; DIGITALSCHULUNG F\u00dcR JUGENDLEITER*INNEN\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.sjr-erlangen.de\\\/WP\\\/#website\",\"url\":\"https:\\\/\\\/www.sjr-erlangen.de\\\/WP\\\/\",\"name\":\"SJR Erlangen\",\"description\":\"Herzlich willkommen auf den Seiten des Stadtjugendrings Erlangen!\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.sjr-erlangen.de\\\/WP\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"ENTF\u00c4LLT - DIGITAL TOTAL - DIGITALSCHULUNG F\u00dcR JUGENDLEITER*INNEN - SJR Erlangen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.sjr-erlangen.de\/WP\/event\/digital-total-digitalschulung-fuer-jugendleiterinnen\/","og_locale":"de_DE","og_type":"article","og_title":"ENTF\u00c4LLT - DIGITAL TOTAL - DIGITALSCHULUNG F\u00dcR JUGENDLEITER*INNEN - SJR Erlangen","og_description":"DIGITALSCHULUNG F\u00dcR JUGENDLEITER*INNEN Digital Total ist eine Mischung aus Ausprobieren und Erlernen neuer digitaler Methoden,\u00a0welche die Arbeit mit Jugendlichen spannend und ergebnisreich machen k\u00f6nnen. Der Stadtjugendring hat einen beachtlichen Digital-Verleih-Katalog [&hellip;]","og_url":"https:\/\/www.sjr-erlangen.de\/WP\/event\/digital-total-digitalschulung-fuer-jugendleiterinnen\/","og_site_name":"SJR Erlangen","article_modified_time":"2024-11-14T16:53:55+00:00","og_image":[{"width":300,"height":200,"url":"https:\/\/www.sjr-erlangen.de\/WP\/wp-content\/uploads\/2023\/07\/DigitalTotal.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.sjr-erlangen.de\/WP\/event\/digital-total-digitalschulung-fuer-jugendleiterinnen\/","url":"https:\/\/www.sjr-erlangen.de\/WP\/event\/digital-total-digitalschulung-fuer-jugendleiterinnen\/","name":"ENTF\u00c4LLT - DIGITAL TOTAL - DIGITALSCHULUNG F\u00dcR JUGENDLEITER*INNEN - SJR Erlangen","isPartOf":{"@id":"https:\/\/www.sjr-erlangen.de\/WP\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.sjr-erlangen.de\/WP\/event\/digital-total-digitalschulung-fuer-jugendleiterinnen\/#primaryimage"},"image":{"@id":"https:\/\/www.sjr-erlangen.de\/WP\/event\/digital-total-digitalschulung-fuer-jugendleiterinnen\/#primaryimage"},"thumbnailUrl":"https:\/\/www.sjr-erlangen.de\/WP\/wp-content\/uploads\/2023\/07\/DigitalTotal.jpg","datePublished":"2023-07-14T12:10:03+00:00","dateModified":"2024-11-14T16:53:55+00:00","breadcrumb":{"@id":"https:\/\/www.sjr-erlangen.de\/WP\/event\/digital-total-digitalschulung-fuer-jugendleiterinnen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.sjr-erlangen.de\/WP\/event\/digital-total-digitalschulung-fuer-jugendleiterinnen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/www.sjr-erlangen.de\/WP\/event\/digital-total-digitalschulung-fuer-jugendleiterinnen\/#primaryimage","url":"https:\/\/www.sjr-erlangen.de\/WP\/wp-content\/uploads\/2023\/07\/DigitalTotal.jpg","contentUrl":"https:\/\/www.sjr-erlangen.de\/WP\/wp-content\/uploads\/2023\/07\/DigitalTotal.jpg","width":300,"height":200},{"@type":"BreadcrumbList","@id":"https:\/\/www.sjr-erlangen.de\/WP\/event\/digital-total-digitalschulung-fuer-jugendleiterinnen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.sjr-erlangen.de\/WP\/"},{"@type":"ListItem","position":2,"name":"Veranstaltungen","item":"https:\/\/www.sjr-erlangen.de\/WP\/events\/"},{"@type":"ListItem","position":3,"name":"ENTF\u00c4LLT &#8211; DIGITAL TOTAL &#8211; DIGITALSCHULUNG F\u00dcR JUGENDLEITER*INNEN"}]},{"@type":"WebSite","@id":"https:\/\/www.sjr-erlangen.de\/WP\/#website","url":"https:\/\/www.sjr-erlangen.de\/WP\/","name":"SJR Erlangen","description":"Herzlich willkommen auf den Seiten des Stadtjugendrings Erlangen!","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.sjr-erlangen.de\/WP\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/www.sjr-erlangen.de\/WP\/wp-json\/wp\/v2\/tribe_events\/5952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.sjr-erlangen.de\/WP\/wp-json\/wp\/v2\/tribe_events"}],"about":[{"href":"https:\/\/www.sjr-erlangen.de\/WP\/wp-json\/wp\/v2\/types\/tribe_events"}],"author":[{"embeddable":true,"href":"https:\/\/www.sjr-erlangen.de\/WP\/wp-json\/wp\/v2\/users\/1"}],"version-history":[{"count":7,"href":"https:\/\/www.sjr-erlangen.de\/WP\/wp-json\/wp\/v2\/tribe_events\/5952\/revisions"}],"predecessor-version":[{"id":7234,"href":"https:\/\/www.sjr-erlangen.de\/WP\/wp-json\/wp\/v2\/tribe_events\/5952\/revisions\/7234"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.sjr-erlangen.de\/WP\/wp-json\/wp\/v2\/media\/5953"}],"wp:attachment":[{"href":"https:\/\/www.sjr-erlangen.de\/WP\/wp-json\/wp\/v2\/media?parent=5952"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.sjr-erlangen.de\/WP\/wp-json\/wp\/v2\/tags?post=5952"},{"taxonomy":"tribe_events_cat","embeddable":true,"href":"https:\/\/www.sjr-erlangen.de\/WP\/wp-json\/wp\/v2\/tribe_events_cat?post=5952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}